{"id":1080,"date":"2014-12-15T12:47:23","date_gmt":"2014-12-15T12:47:23","guid":{"rendered":"http:\/\/poloconsult.com\/?p=1080"},"modified":"2014-12-26T23:58:49","modified_gmt":"2014-12-26T23:58:49","slug":"les-expressions-faciales-dun-cheval","status":"publish","type":"post","link":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/","title":{"rendered":"Les expressions faciales d&rsquo;un cheval"},"content":{"rendered":"<p>Les chevaux utilisent leurs expressions faciales pour communiquer. Leurs humeurs peuvent facilement s\u2019identifier gr\u00e2ce \u00e0 leurs naseaux, leurs yeux et leurs oreilles.<\/p>\n<p>Les oreilles constituent la partie qui exprime particuli\u00e8rement bien les humeurs du cheval:<br \/>\n&#8211; tourn\u00e9es vers l&rsquo;arri\u00e8re: il est \u00e0 l&rsquo;\u00e9coute derri\u00e8re lui.<br \/>\n&#8211; point\u00e9es vers l&rsquo;avant avec la t\u00eate droite: il est curieux.<br \/>\n&#8211; tourn\u00e9es l\u00e9g\u00e8rement vers l&rsquo;arri\u00e8re: il s&rsquo;ennuie.<br \/>\n&#8211; plaqu\u00e9es en arri\u00e8re: il est mena\u00e7ant.<\/p>\n<p>Voici les signes corporels repr\u00e9sentant les 4 attitudes principales:<br \/>\n&#8211; En alerte: le cheval a la t\u00eate haute, ses yeux sont bien ouverts et les oreilles pointent vers l&rsquo;avant.<br \/>\n&#8211; La peur: un cheval est facilement effray\u00e9. Il incline alors sa t\u00eate en arri\u00e8re, ses yeux sont grands et le blanc de l&rsquo;oeil est particuli\u00e8rement visible.<br \/>\n&#8211; La menace: sa t\u00eate est l\u00e9g\u00e8rement sur\u00e9lev\u00e9e et il montre les dents. Il peut \u00e9galement plaquer ses oreilles en arri\u00e8re et \u00e9ventuellement avoir une forte respiration, que l&rsquo;on peut voir gr\u00e2ce \u00e0 ses naseaux qui s&rsquo;enflamment.<br \/>\n&#8211; D\u00e9tendu: le cheval se tient normalement. Ses gestes sont doux et tendres.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1080 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a rel='prettyPhoto[gallery]' href='https:\/\/www.spiritofpolo-press.com\/fr\/horse-facial-expressions\/murmure-oreille-cheval\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval-150x150.jpg 150w, https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval-304x304.jpg 304w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a rel='prettyPhoto[gallery]' href='https:\/\/www.spiritofpolo-press.com\/fr\/horse-facial-expressions\/2773495650_1_result\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/2773495650_1_result-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/2773495650_1_result-150x150.jpg 150w, https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/2773495650_1_result-304x304.jpg 304w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a rel='prettyPhoto[gallery]' href='https:\/\/www.spiritofpolo-press.com\/fr\/horse-facial-expressions\/image21_result\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/image21_result-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/image21_result-150x150.jpg 150w, https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/image21_result-304x304.jpg 304w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a rel='prettyPhoto[gallery]' href='https:\/\/www.spiritofpolo-press.com\/fr\/horse-facial-expressions\/4_acjq2_result\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/4_AcJQ2_result-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/4_AcJQ2_result-150x150.jpg 150w, https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/4_AcJQ2_result-304x304.jpg 304w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a rel='prettyPhoto[gallery]' href='https:\/\/www.spiritofpolo-press.com\/fr\/horse-facial-expressions\/cheval-libre_result\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/cheval-libre_result-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Les chevaux utilisent leurs expressions faciales pour communiquer. Leurs humeurs peuvent facilement s\u2019identifier gr\u00e2ce \u00e0 leurs naseaux, leurs yeux et leurs oreilles. Les oreilles constituent la partie qui exprime particuli\u00e8rement bien les humeurs du cheval: &#8211; tourn\u00e9es vers l&rsquo;arri\u00e8re: il est \u00e0 l&rsquo;\u00e9coute derri\u00e8re lui. &#8211; point\u00e9es vers l&rsquo;avant avec la t\u00eate droite: il est &hellip;<\/p>\n","protected":false},"author":2,"featured_media":362,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[464],"tags":[461,634,635,1064],"class_list":["post-1080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saviez-vous","tag-cheval","tag-expressions","tag-faciales","tag-polo-fr-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les expressions faciales d&#039;un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les expressions faciales d&#039;un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS\" \/>\n<meta property=\"og:description\" content=\"Les chevaux utilisent leurs expressions faciales pour communiquer. Leurs humeurs peuvent facilement s\u2019identifier gr\u00e2ce \u00e0 leurs naseaux, leurs yeux et leurs oreilles. Les oreilles constituent la partie qui exprime particuli\u00e8rement bien les humeurs du cheval: &#8211; tourn\u00e9es vers l&rsquo;arri\u00e8re: il est \u00e0 l&rsquo;\u00e9coute derri\u00e8re lui. &#8211; point\u00e9es vers l&rsquo;avant avec la t\u00eate droite: il est &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\" \/>\n<meta property=\"og:site_name\" content=\"SPIRIT OF POLO &amp; JUMPING - PRESS\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-15T12:47:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-26T23:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"autores\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"autores\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\"},\"author\":{\"name\":\"autores\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa\"},\"headline\":\"Les expressions faciales d&rsquo;un cheval\",\"datePublished\":\"2014-12-15T12:47:23+00:00\",\"dateModified\":\"2014-12-26T23:58:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\"},\"wordCount\":208,\"image\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg\",\"keywords\":[\"Cheval\",\"Expressions\",\"Faciales\",\"polo\"],\"articleSection\":[\"SAVIEZ-VOUS?\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\",\"name\":\"Les expressions faciales d'un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS\",\"isPartOf\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg\",\"datePublished\":\"2014-12-15T12:47:23+00:00\",\"dateModified\":\"2014-12-26T23:58:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg\",\"contentUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg\",\"width\":1280,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.spiritofpolo-press.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les expressions faciales d&rsquo;un cheval\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#website\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/\",\"name\":\"SPIRIT OF POLO &amp; JUMPING - PRESS\",\"description\":\"Polo &amp; Jumping Worldwide Information &amp; Photos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.spiritofpolo-press.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa\",\"name\":\"autores\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g\",\"caption\":\"autores\"},\"url\":\"https:\/\/www.spiritofpolo-press.com\/fr\/author\/autores\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les expressions faciales d'un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/","og_locale":"fr_FR","og_type":"article","og_title":"Les expressions faciales d'un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS","og_description":"Les chevaux utilisent leurs expressions faciales pour communiquer. Leurs humeurs peuvent facilement s\u2019identifier gr\u00e2ce \u00e0 leurs naseaux, leurs yeux et leurs oreilles. Les oreilles constituent la partie qui exprime particuli\u00e8rement bien les humeurs du cheval: &#8211; tourn\u00e9es vers l&rsquo;arri\u00e8re: il est \u00e0 l&rsquo;\u00e9coute derri\u00e8re lui. &#8211; point\u00e9es vers l&rsquo;avant avec la t\u00eate droite: il est &hellip;","og_url":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/","og_site_name":"SPIRIT OF POLO &amp; JUMPING - PRESS","article_published_time":"2014-12-15T12:47:23+00:00","article_modified_time":"2014-12-26T23:58:49+00:00","og_image":[{"width":1280,"height":850,"url":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg","type":"image\/jpeg"}],"author":"autores","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"autores","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#article","isPartOf":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/"},"author":{"name":"autores","@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa"},"headline":"Les expressions faciales d&rsquo;un cheval","datePublished":"2014-12-15T12:47:23+00:00","dateModified":"2014-12-26T23:58:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/"},"wordCount":208,"image":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage"},"thumbnailUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg","keywords":["Cheval","Expressions","Faciales","polo"],"articleSection":["SAVIEZ-VOUS?"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/","url":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/","name":"Les expressions faciales d'un cheval - SPIRIT OF POLO &amp; JUMPING - PRESS","isPartOf":{"@id":"https:\/\/www.spiritofpolo-press.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage"},"image":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage"},"thumbnailUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg","datePublished":"2014-12-15T12:47:23+00:00","dateModified":"2014-12-26T23:58:49+00:00","author":{"@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa"},"breadcrumb":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#primaryimage","url":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg","contentUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2014\/12\/murmure-oreille-cheval.jpg","width":1280,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/les-expressions-faciales-dun-cheval\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.spiritofpolo-press.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les expressions faciales d&rsquo;un cheval"}]},{"@type":"WebSite","@id":"https:\/\/www.spiritofpolo-press.com\/#website","url":"https:\/\/www.spiritofpolo-press.com\/","name":"SPIRIT OF POLO &amp; JUMPING - PRESS","description":"Polo &amp; Jumping Worldwide Information &amp; Photos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.spiritofpolo-press.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/3f63e091802760c6291c2cd464ecaffa","name":"autores","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be7ea8384496361796c167fdd4aae98b460ca3019b5ad44cefdc3490c7fad490?s=96&d=mm&r=g","caption":"autores"},"url":"https:\/\/www.spiritofpolo-press.com\/fr\/author\/autores\/"}]}},"_links":{"self":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/1080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":1,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1083,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/media\/362"}],"wp:attachment":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}