{"id":5685,"date":"2016-05-18T16:47:13","date_gmt":"2016-05-18T16:47:13","guid":{"rendered":"http:\/\/poloconsult.com\/?p=5685"},"modified":"2016-05-18T16:47:50","modified_gmt":"2016-05-18T16:47:50","slug":"decouvrir-le-paddock-polo","status":"publish","type":"post","link":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/","title":{"rendered":"D\u00e9couvrir le Paddock Polo"},"content":{"rendered":"<p>Rencontre avec Pascal Jamet, d\u00e9l\u00e9gu\u00e9 technique de Paddock Polo et expert f\u00e9d\u00e9ral<br \/>\n\u00a9 FFE \/ Maindru<\/p>\n<p><strong>Paddock Polo \/ Grand polo :<br \/>\nQuelle diff\u00e9rence ?<\/strong><br \/>\n\u00ab Le paddock polo est plus facile \u00e0 mettre en pratique dans les clubs et chez les cavaliers d\u00e9butants.<br \/>\nDes initiations peuvent \u00eatre faites en carri\u00e8re et les matchs ne n\u00e9cessitent qu\u2019un seul cheval par cavalier, \u00e0 la diff\u00e9rence du Grand Polo. La balle est plus grosse et en cuir, elle s\u2019adapte \u00e0 tous les types de terrain.<br \/>\nCes am\u00e9nagements permettent une d\u00e9couverte facilit\u00e9e de la pratique, ils sont un tremplin pour l\u2019\u00e9quitation et pour le Grand Polo. \u00bb<\/p>\n<p><strong>O\u00f9 en est le Paddock Polo ?<\/strong><br \/>\n\u00ab Gr\u00e2ce \u00e0 des \u00e9v\u00e9nements comme le Grand Tournoi, nous pouvons voir chaque ann\u00e9e le niveau des joueurs progresser. Ce qui est de bon augure pour le Grand Polo, puisque les cavaliers de Paddock Polo sont amen\u00e9s \u00e0 pratiquer le Grand Polo.<br \/>\nLe niveau des joueurs et des matchs a augment\u00e9 dans les cat\u00e9gories hautes du Paddock Polo. Les cat\u00e9gories 3 restent toujours adapt\u00e9es aux nouveaux passionn\u00e9s.<br \/>\nLe niveau des joueurs fran\u00e7ais professionnels de Grand Polo a lui aussi augment\u00e9. Aujourd\u2019hui, tous les meilleurs fran\u00e7ais sont pass\u00e9s par le Paddock Polo et par le Grand Tournoi. La hausse du nombre de joueurs nous permet aussi d\u2019avoir une meilleure s\u00e9lection pour le haut niveau. \u00bb<\/p>\n<p><strong>Comment d\u00e9velopper la discipline ?<\/strong><br \/>\n\u00ab Nous aidons les enseignants en proposant des formations au Paddock Polo. Elles sont mises en place par les Comit\u00e9s R\u00e9gionaux d\u2019Equitation. Les stages sont mis en place sur 3 trimestres, une premi\u00e8re initiation est faite, nous revenons au trimestre suivant pour leur apporter de nouvelles connaissances. C\u2019est un apprentissage progressif en plusieurs \u00e9tapes.<br \/>\nAu programme : bases du jeu puis progressivement phases de jeu, matchs et diff\u00e9rentes strat\u00e9gies.<br \/>\nLes stages clubs organis\u00e9s sur le Parc \u00e9questre f\u00e9d\u00e9ral ont permis \u00e0 plusieurs clubs de d\u00e9couvrir la pratique et par la suite de vouloir suivre la formation. \u00bb<br \/>\nPascal Jamet<\/p>\n<div class=\"su-note\"  style=\"border-color:#2fb1d2;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#49cbec;border-color:#ffffff;color:#273739;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\">PADDOCK POLO<br \/>\n\u00ab Les dimensions officielles d\u2019un terrain de Paddock Polo sont de 150 x 80 m\u00e8tres. Les entra\u00eenements et matchs internes peuvent toutefois se faire sur des dimensions inf\u00e9rieures, en fonction de la taille de votre carri\u00e8re ou man\u00e8ge et du niveau des joueurs. \u00bb<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rencontre avec Pascal Jamet, d\u00e9l\u00e9gu\u00e9 technique de Paddock Polo et expert f\u00e9d\u00e9ral \u00a9 FFE \/ Maindru Paddock Polo \/ Grand polo : Quelle diff\u00e9rence ? \u00ab Le paddock polo est plus facile \u00e0 mettre en pratique dans les clubs et chez les cavaliers d\u00e9butants. Des initiations peuvent \u00eatre faites en carri\u00e8re et les matchs ne &hellip;<\/p>\n","protected":false},"author":1,"featured_media":5686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14,16],"tags":[901,1561],"class_list":["post-5685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-info","tag-paddock-polo-fr","tag-pascal-jamet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS\" \/>\n<meta property=\"og:description\" content=\"Rencontre avec Pascal Jamet, d\u00e9l\u00e9gu\u00e9 technique de Paddock Polo et expert f\u00e9d\u00e9ral \u00a9 FFE \/ Maindru Paddock Polo \/ Grand polo : Quelle diff\u00e9rence ? \u00ab Le paddock polo est plus facile \u00e0 mettre en pratique dans les clubs et chez les cavaliers d\u00e9butants. Des initiations peuvent \u00eatre faites en carri\u00e8re et les matchs ne &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\" \/>\n<meta property=\"og:site_name\" content=\"SPIRIT OF POLO &amp; JUMPING - PRESS\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Poloconsult\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T16:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-18T16:47:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"poloconsult\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"poloconsult\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\"},\"author\":{\"name\":\"poloconsult\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4\"},\"headline\":\"D\u00e9couvrir le Paddock Polo\",\"datePublished\":\"2016-05-18T16:47:13+00:00\",\"dateModified\":\"2016-05-18T16:47:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\"},\"wordCount\":410,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg\",\"keywords\":[\"Paddock Polo\",\"Pascal Jamet\"],\"articleSection\":[\"NEWS\",\"Info\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\",\"name\":\"D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS\",\"isPartOf\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg\",\"datePublished\":\"2016-05-18T16:47:13+00:00\",\"dateModified\":\"2016-05-18T16:47:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg\",\"contentUrl\":\"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg\",\"width\":3552,\"height\":2368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.spiritofpolo-press.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9couvrir le Paddock Polo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#website\",\"url\":\"https:\/\/www.spiritofpolo-press.com\/\",\"name\":\"SPIRIT OF POLO &amp; JUMPING - PRESS\",\"description\":\"Polo &amp; Jumping Worldwide Information &amp; Photos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.spiritofpolo-press.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4\",\"name\":\"poloconsult\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g\",\"caption\":\"poloconsult\"},\"sameAs\":[\"http:\/\/www.poloconsult.com\",\"https:\/\/www.facebook.com\/Poloconsult\"],\"url\":\"https:\/\/www.spiritofpolo-press.com\/fr\/author\/poloconsult\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS","og_description":"Rencontre avec Pascal Jamet, d\u00e9l\u00e9gu\u00e9 technique de Paddock Polo et expert f\u00e9d\u00e9ral \u00a9 FFE \/ Maindru Paddock Polo \/ Grand polo : Quelle diff\u00e9rence ? \u00ab Le paddock polo est plus facile \u00e0 mettre en pratique dans les clubs et chez les cavaliers d\u00e9butants. Des initiations peuvent \u00eatre faites en carri\u00e8re et les matchs ne &hellip;","og_url":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/","og_site_name":"SPIRIT OF POLO &amp; JUMPING - PRESS","article_author":"https:\/\/www.facebook.com\/Poloconsult","article_published_time":"2016-05-18T16:47:13+00:00","article_modified_time":"2016-05-18T16:47:50+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo-1024x683.jpg","type":"image\/jpeg"}],"author":"poloconsult","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"poloconsult","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#article","isPartOf":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/"},"author":{"name":"poloconsult","@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4"},"headline":"D\u00e9couvrir le Paddock Polo","datePublished":"2016-05-18T16:47:13+00:00","dateModified":"2016-05-18T16:47:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/"},"wordCount":410,"commentCount":0,"image":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg","keywords":["Paddock Polo","Pascal Jamet"],"articleSection":["NEWS","Info"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/","url":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/","name":"D\u00e9couvrir le Paddock Polo - SPIRIT OF POLO &amp; JUMPING - PRESS","isPartOf":{"@id":"https:\/\/www.spiritofpolo-press.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage"},"image":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg","datePublished":"2016-05-18T16:47:13+00:00","dateModified":"2016-05-18T16:47:50+00:00","author":{"@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4"},"breadcrumb":{"@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#primaryimage","url":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg","contentUrl":"https:\/\/www.spiritofpolo-press.com\/wp-content\/uploads\/2016\/05\/Focus-sur-le-Paddock-Polo.jpg","width":3552,"height":2368},{"@type":"BreadcrumbList","@id":"https:\/\/www.spiritofpolo-press.com\/fr\/decouvrir-le-paddock-polo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.spiritofpolo-press.com\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9couvrir le Paddock Polo"}]},{"@type":"WebSite","@id":"https:\/\/www.spiritofpolo-press.com\/#website","url":"https:\/\/www.spiritofpolo-press.com\/","name":"SPIRIT OF POLO &amp; JUMPING - PRESS","description":"Polo &amp; Jumping Worldwide Information &amp; Photos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.spiritofpolo-press.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.spiritofpolo-press.com\/#\/schema\/person\/e28450b465807799918cbf6f167dd5e4","name":"poloconsult","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd4c3d89fa6d49a9b4d9244579028badf711ffe055565c7786d709eff6c42fdf?s=96&d=mm&r=g","caption":"poloconsult"},"sameAs":["http:\/\/www.poloconsult.com","https:\/\/www.facebook.com\/Poloconsult"],"url":"https:\/\/www.spiritofpolo-press.com\/fr\/author\/poloconsult\/"}]}},"_links":{"self":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/5685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/comments?post=5685"}],"version-history":[{"count":1,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/5685\/revisions"}],"predecessor-version":[{"id":5687,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/posts\/5685\/revisions\/5687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/media\/5686"}],"wp:attachment":[{"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/media?parent=5685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/categories?post=5685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spiritofpolo-press.com\/fr\/wp-json\/wp\/v2\/tags?post=5685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}